{"id":381,"date":"2018-03-13T06:17:10","date_gmt":"2018-03-13T06:17:10","guid":{"rendered":"https:\/\/space.xtemos.com\/demo\/hitek\/?p=381"},"modified":"2024-01-19T15:33:38","modified_gmt":"2024-01-19T15:33:38","slug":"a-evolucao-do-copo-plastico","status":"publish","type":"post","link":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/a-evolucao-do-copo-plastico\/","title":{"rendered":"La evoluci\u00f3n del vaso de pl\u00e1stico"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"381\" class=\"elementor elementor-381\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-199450cc elementor-section-boxed elementor-section-height-default elementor-section-height-default xts-section-disabled\" data-id=\"199450cc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7843b1ac\" data-id=\"7843b1ac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba6da2b xts-scheme-inherit xts-textalign-inherit elementor-widget elementor-widget-text-editor\" data-id=\"ba6da2b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Los vasos de pl\u00e1stico, sin duda, han cambiado el mundo. Se encuentran en estadios y partidos deportivos, as\u00ed como en picnics familiares, hospitales, escuelas y eventos... La historia de los vasos de pl\u00e1stico se remonta a la d\u00e9cada de 1960, pero antes de su invenci\u00f3n, los vasos de papel se usaban de forma similar.<\/p>\n\n<p>Aqu\u00ed revivimos un poco de la historia de las gafas y nos atrevemos a mirar hacia el futuro. \u00bfC\u00f3mo ser\u00e1n las gafas dentro de 20, 40 o 100 a\u00f1os? \ud83d\ude09<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff1e2c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default xts-section-disabled\" data-id=\"ff1e2c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2738fd84\" data-id=\"2738fd84\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45b6236c elementor-widget elementor-widget-xts_title\" data-id=\"45b6236c\" data-element_type=\"widget\" data-widget_type=\"xts_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"xts-section-heading xts-reset-mb-10 xts-reset-last xts-textalign-left\" data-animation-delay=\"\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<h4 class=\"xts-section-title title xts-design-default xts-fontsize-l\">\r\n\t\t\t\t\t\t<span class=\"xts-section-title-text\" data-elementor-setting-key=\"title\">\r\n\t\t\t\t\t\t\tLos comienzos... \u00a1en la China imperial!\t\t\t\t\t\t<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<\/h4>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36caa4af xts-scheme-inherit xts-textalign-inherit elementor-widget elementor-widget-text-editor\" data-id=\"36caa4af\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Existe documentaci\u00f3n de la existencia de vasos de papel en la China imperial, donde el papel se invent\u00f3 alrededor del siglo II a. C. Los vasos de papel se conoc\u00edan como chih pei y se utilizaban para servir t\u00e9.<\/p>\n\n<p>Los vasos de papel eran de diferentes tama\u00f1os y colores, y estaban adornados con dise\u00f1os. La evidencia textual de su existencia aparece en una descripci\u00f3n de las posesiones de la familia Yu en Hangzhou.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b5307fe elementor-section-boxed elementor-section-height-default elementor-section-height-default xts-section-disabled\" data-id=\"b5307fe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bdd4c54\" data-id=\"bdd4c54\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e46e04c elementor-widget elementor-widget-xts_title\" data-id=\"e46e04c\" data-element_type=\"widget\" data-widget_type=\"xts_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"xts-section-heading xts-reset-mb-10 xts-reset-last xts-textalign-left\" data-animation-delay=\"\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<h4 class=\"xts-section-title title xts-design-default xts-fontsize-l\">\r\n\t\t\t\t\t\t<span class=\"xts-section-title-text\" data-elementor-setting-key=\"title\">\r\n\t\t\t\t\t\t\tVaso de pl\u00e1stico Dixie\t\t\t\t\t\t<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<\/h4>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5e463b xts-scheme-inherit xts-textalign-inherit elementor-widget elementor-widget-text-editor\" data-id=\"f5e463b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tEl precursor del vaso de pl\u00e1stico moderno fue el <a href=\"https:\/\/en.wikipedia.org\/wiki\/Paper_cup\" target=\"_blank\" rel=\"noopener\">Vasos Dixie<\/a>Fabricado por primera vez en 1908. Inicialmente fabricado en papel, la empresa vio la necesidad de un vaso desechable y cambi\u00f3 por completo la forma de beber. Antes de la invenci\u00f3n de estos vasos, la gente beb\u00eda de vasos o barriles de agua comunes, donde eran susceptibles a los g\u00e9rmenes y enfermedades de otros usuarios. Estos vasos ten\u00edan una peque\u00f1a capa de cera en el interior que evitaba derrames; sin embargo, segu\u00edan siendo de papel.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-82d97b1\" data-id=\"82d97b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10bc4be elementor-widget elementor-widget-image\" data-id=\"10bc4be\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"961\" src=\"image\/jpeg;base64,\/9j\/4AAQSkZJRgABAQEAYABgAAD\/\/gA7Q1JFQVRPUjogZ2QtanBlZyB2MS4wICh1c2luZyBJSkcgSlBFRyB2ODApLCBxdWFsaXR5ID0gODIK\/9sAQwAGBAQFBAQGBQUFBgYGBwkOCQkICAkSDQ0KDhUSFhYVEhQUFxohHBcYHxkUFB0nHR8iIyUlJRYcKSwoJCshJCUk\/9sAQwEGBgYJCAkRCQkRJBgUGCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQk\/8AAEQgADQAKAwEiAAIRAQMRAf\/EAB8AAAEFAQEBAQEBAAAAAAAAAAABAgMEBQYHCAkKC\/\/EALUQAAIBAwMCBAMFBQQEAAABfQECAwAEEQUSITFBBhNRYQcicRQygZGhCCNCscEVUtHwJDNicoIJChYXGBkaJSYnKCkqNDU2Nzg5OkNERUZHSElKU1RVVldYWVpjZGVmZ2hpanN0dXZ3eHl6g4SFhoeIiYqSk5SVlpeYmZqio6Slpqeoqaqys7S1tre4ubrCw8TFxsfIycrS09TV1tfY2drh4uPk5ebn6Onq8fLz9PX29\/j5+v\/EAB8BAAMBAQEBAQEBAQEAAAAAAAABAgMEBQYHCAkKC\/\/EALURAAIBAgQEAwQHBQQEAAECdwABAgMRBAUhMQYSQVEHYXETIjKBCBRCkaGxwQkjM1LwFWJy0QoWJDThJfEXGBkaJicoKSo1Njc4OTpDREVGR0hJSlNUVVZXWFlaY2RlZmdoaWpzdHV2d3h5eoKDhIWGh4iJipKTlJWWl5iZmqKjpKWmp6ipqrKztLW2t7i5usLDxMXGx8jJytLT1NXW19jZ2uLj5OXm5+jp6vLz9PX29\/j5+v\/aAAwDAQACEQMRAD8Az9K8JRjUb2DVLWeOOGza4XPyEYzzz16Vmf2CfSse28Ya3YM7C8NwXj8ljcqJSU\/u\/Nnj26VUHjHV0G1JyqjgKrOAB6AbqUM2km3a9zjlQg0ltY\/\/2Q==\" class=\"attachment-full size-full wp-image-3980 xts-lazy-load xts-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-xts-src=\"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/copo-plastico-dixie-copopalhinhas.jpeg\" data-srcset=\"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/copo-plastico-dixie-copopalhinhas.jpeg 800w, https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/copo-plastico-dixie-copopalhinhas-250x300.jpeg 250w, https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/copo-plastico-dixie-copopalhinhas-768x923.jpeg 768w, https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/copo-plastico-dixie-copopalhinhas-450x541.jpeg 450w, https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/copo-plastico-dixie-copopalhinhas-300x360.jpeg 300w\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2003b9 xts-scheme-inherit xts-textalign-inherit elementor-widget elementor-widget-text-editor\" data-id=\"b2003b9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote>Imagen de la f\u00e1brica de vasos Dixie en EE.UU.<\/blockquote>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b13e537 elementor-section-boxed elementor-section-height-default elementor-section-height-default xts-section-disabled\" data-id=\"b13e537\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4836cd3\" data-id=\"4836cd3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f437a6 elementor-widget elementor-widget-image\" data-id=\"8f437a6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"736\" height=\"1003\" src=\"image\/jpeg;base64,\/9j\/4AAQSkZJRgABAQEAYABgAAD\/\/gA7Q1JFQVRPUjogZ2QtanBlZyB2MS4wICh1c2luZyBJSkcgSlBFRyB2ODApLCBxdWFsaXR5ID0gODIK\/9sAQwAGBAQFBAQGBQUFBgYGBwkOCQkICAkSDQ0KDhUSFhYVEhQUFxohHBcYHxkUFB0nHR8iIyUlJRYcKSwoJCshJCUk\/9sAQwEGBgYJCAkRCQkRJBgUGCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQk\/8AAEQgADgAKAwEiAAIRAQMRAf\/EAB8AAAEFAQEBAQEBAAAAAAAAAAABAgMEBQYHCAkKC\/\/EALUQAAIBAwMCBAMFBQQEAAABfQECAwAEEQUSITFBBhNRYQcicRQygZGhCCNCscEVUtHwJDNicoIJChYXGBkaJSYnKCkqNDU2Nzg5OkNERUZHSElKU1RVVldYWVpjZGVmZ2hpanN0dXZ3eHl6g4SFhoeIiYqSk5SVlpeYmZqio6Slpqeoqaqys7S1tre4ubrCw8TFxsfIycrS09TV1tfY2drh4uPk5ebn6Onq8fLz9PX29\/j5+v\/EAB8BAAMBAQEBAQEBAQEAAAAAAAABAgMEBQYHCAkKC\/\/EALURAAIBAgQEAwQHBQQEAAECdwABAgMRBAUhMQYSQVEHYXETIjKBCBRCkaGxwQkjM1LwFWJy0QoWJDThJfEXGBkaJicoKSo1Njc4OTpDREVGR0hJSlNUVVZXWFlaY2RlZmdoaWpzdHV2d3h5eoKDhIWGh4iJipKTlJWWl5iZmqKjpKWmp6ipqrKztLW2t7i5usLDxMXGx8jJytLT1NXW19jZ2uLj5OXm5+jp6vLz9PX29\/j5+v\/aAAwDAQACEQMRAD8A6Txq\/ifUfENv\/Y+vtYaTJblYvJ43Tqx37zgnGCvt1qvY+PNdWyt1lltJZBGod8r8xxyeveuqk+H2kG7jvs3byQtuiUzsFUbs4I7jvz39K6KPy0jVNv3QBwMV4DqRSSsemoNu5\/\/Z\" class=\"attachment-full size-full wp-image-3981 xts-lazy-load xts-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 736px) 100vw, 736px\" data-xts-src=\"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/dixie-cups-copopalhinhas.jpeg\" data-srcset=\"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/dixie-cups-copopalhinhas.jpeg 736w, https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/dixie-cups-copopalhinhas-220x300.jpeg 220w, https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/dixie-cups-copopalhinhas-734x1000.jpeg 734w, https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/dixie-cups-copopalhinhas-450x613.jpeg 450w, https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/dixie-cups-copopalhinhas-300x409.jpeg 300w\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dee2d1a\" data-id=\"dee2d1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2326049 elementor-widget elementor-widget-xts_title\" data-id=\"2326049\" data-element_type=\"widget\" data-widget_type=\"xts_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"xts-section-heading xts-reset-mb-10 xts-reset-last xts-textalign-left\" data-animation-delay=\"\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<h4 class=\"xts-section-title title xts-design-default xts-fontsize-l\">\r\n\t\t\t\t\t\t<span class=\"xts-section-title-text\" data-elementor-setting-key=\"title\">\r\n\t\t\t\t\t\t\tVaso de pl\u00e1stico de una sola porci\u00f3n\t\t\t\t\t\t<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<\/h4>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1c0481 xts-scheme-inherit xts-textalign-inherit elementor-widget elementor-widget-text-editor\" data-id=\"f1c0481\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Un \u00e9xito desde el primer lanzamiento de los vasos Dixie. Los primeros en adoptarlos fueron los ferrocarriles, que reemplazaron los vasos compartidos por vasos desechables.<\/p>\n\n<p>Poco despu\u00e9s, los hospitales tambi\u00e9n dejaron de usar vasos de papel. Esto evit\u00f3 la contaminaci\u00f3n cruzada y la propagaci\u00f3n de enfermedades entre los pacientes. Estos mismos grupos cambiaron a vasos de espuma tras su invenci\u00f3n, pero finalmente optaron por el pl\u00e1stico por ser menos perjudicial para el medio ambiente.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d8df841 elementor-section-boxed elementor-section-height-default elementor-section-height-default xts-section-disabled\" data-id=\"d8df841\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1bee5b8\" data-id=\"1bee5b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e5ef2f elementor-widget elementor-widget-xts_title\" data-id=\"3e5ef2f\" data-element_type=\"widget\" data-widget_type=\"xts_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"xts-section-heading xts-reset-mb-10 xts-reset-last xts-textalign-left\" data-animation-delay=\"\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<h4 class=\"xts-section-title title xts-design-default xts-fontsize-l\">\r\n\t\t\t\t\t\t<span class=\"xts-section-title-text\" data-elementor-setting-key=\"title\">\r\n\t\t\t\t\t\t\tVaso de pl\u00e1stico en la d\u00e9cada de 1960\t\t\t\t\t\t<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<\/h4>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2224de xts-scheme-inherit xts-textalign-inherit elementor-widget elementor-widget-text-editor\" data-id=\"d2224de\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>En la d\u00e9cada de 1960, la primera patente para un vaso de pl\u00e1stico en Estados Unidos se otorg\u00f3 a un grupo conocido simplemente como Price et al. La patente, en s\u00ed, correspond\u00eda a un solo vaso y se otorg\u00f3 en 1964.<\/p>\n\n<p>Antes de esto, un hombre llamado Caine patent\u00f3 su idea de un recipiente de pl\u00e1stico de paredes delgadas. En esencia, este recipiente era un vaso de pl\u00e1stico, pero al no catalogarlo como tal, abri\u00f3 la puerta a que otros registraran y patentaran su propia versi\u00f3n del vaso de pl\u00e1stico.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-83eb7dd\" data-id=\"83eb7dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5afe9e0 elementor-widget elementor-widget-image\" data-id=\"5afe9e0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"736\" height=\"946\" src=\"image\/jpeg;base64,\/9j\/4AAQSkZJRgABAQEAYABgAAD\/\/gA7Q1JFQVRPUjogZ2QtanBlZyB2MS4wICh1c2luZyBJSkcgSlBFRyB2ODApLCBxdWFsaXR5ID0gODIK\/9sAQwAGBAQFBAQGBQUFBgYGBwkOCQkICAkSDQ0KDhUSFhYVEhQUFxohHBcYHxkUFB0nHR8iIyUlJRYcKSwoJCshJCUk\/9sAQwEGBgYJCAkRCQkRJBgUGCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQkJCQk\/8AAEQgADQAKAwEiAAIRAQMRAf\/EAB8AAAEFAQEBAQEBAAAAAAAAAAABAgMEBQYHCAkKC\/\/EALUQAAIBAwMCBAMFBQQEAAABfQECAwAEEQUSITFBBhNRYQcicRQygZGhCCNCscEVUtHwJDNicoIJChYXGBkaJSYnKCkqNDU2Nzg5OkNERUZHSElKU1RVVldYWVpjZGVmZ2hpanN0dXZ3eHl6g4SFhoeIiYqSk5SVlpeYmZqio6Slpqeoqaqys7S1tre4ubrCw8TFxsfIycrS09TV1tfY2drh4uPk5ebn6Onq8fLz9PX29\/j5+v\/EAB8BAAMBAQEBAQEBAQEAAAAAAAABAgMEBQYHCAkKC\/\/EALURAAIBAgQEAwQHBQQEAAECdwABAgMRBAUhMQYSQVEHYXETIjKBCBRCkaGxwQkjM1LwFWJy0QoWJDThJfEXGBkaJicoKSo1Njc4OTpDREVGR0hJSlNUVVZXWFlaY2RlZmdoaWpzdHV2d3h5eoKDhIWGh4iJipKTlJWWl5iZmqKjpKWmp6ipqrKztLW2t7i5usLDxMXGx8jJytLT1NXW19jZ2uLj5OXm5+jp6vLz9PX29\/j5+v\/aAAwDAQACEQMRAD8Ax5\/iBFb3b20t7cqhbaSkpGOnAOeOTjjp1rtrQQz2sMzKHaRFYswySSM5JNaNl4c8M3CI76DESy5cmVstkVC\/k27GGONgkZ2KNw4A4HauOFNx1PXxGIjU2\/JI\/9k=\" class=\"attachment-full size-full wp-image-3982 xts-lazy-load xts-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 736px) 100vw, 736px\" data-xts-src=\"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/dixie-cups-coca-cola-copopalhinhas.jpeg\" data-srcset=\"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/dixie-cups-coca-cola-copopalhinhas.jpeg 736w, https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/dixie-cups-coca-cola-copopalhinhas-233x300.jpeg 233w, https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/dixie-cups-coca-cola-copopalhinhas-450x578.jpeg 450w, https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/dixie-cups-coca-cola-copopalhinhas-300x386.jpeg 300w\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea2994b elementor-section-boxed elementor-section-height-default elementor-section-height-default xts-section-disabled\" data-id=\"ea2994b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cbf124c\" data-id=\"cbf124c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12aa8a6 elementor-widget elementor-widget-xts_title\" data-id=\"12aa8a6\" data-element_type=\"widget\" data-widget_type=\"xts_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"xts-section-heading xts-reset-mb-10 xts-reset-last xts-textalign-left\" data-animation-delay=\"\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<h4 class=\"xts-section-title title xts-design-default xts-fontsize-l\">\r\n\t\t\t\t\t\t<span class=\"xts-section-title-text\" data-elementor-setting-key=\"title\">\r\n\t\t\t\t\t\t\tFrenes\u00ed de patentes de vasos de pl\u00e1stico de 1990\t\t\t\t\t\t<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<\/h4>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46c3633 xts-scheme-inherit xts-textalign-inherit elementor-widget elementor-widget-text-editor\" data-id=\"46c3633\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>En la d\u00e9cada de 1990 se presentaron m\u00e1s patentes para vasos de pl\u00e1stico que en cualquier otra d\u00e9cada.<\/p>\n\n<p>En 1996, el <a href=\"https:\/\/www.wilsonplastics.co.nz\/\" target=\"_blank\" rel=\"noopener\">Wilson<\/a> Patent\u00f3 la idea de un vaso de pl\u00e1stico acanalado y otro acanalado. Estas piezas eran m\u00e1s pesadas y duraderas que los vasos de pl\u00e1stico desechables.<\/p>\n\n<p>En 1997, la empresa <a href=\"https:\/\/www.willbrandt.com\/willbrandt\/en\/index.php\" target=\"_blank\" rel=\"noopener\">Willbrandt<\/a> present\u00f3 una patente para un vaso de pl\u00e1stico que encajaba en el portavasos de un autom\u00f3vil y, en 1999, <a href=\"http:\/\/www.jarvismfg.com\/\" target=\"_blank\" rel=\"noopener\">Jarvis<\/a> registr\u00f3 un vidrio con hoyuelos.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11f20e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default xts-section-disabled\" data-id=\"11f20e9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d3746c2\" data-id=\"d3746c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb6d841 elementor-widget elementor-widget-xts_title\" data-id=\"cb6d841\" data-element_type=\"widget\" data-widget_type=\"xts_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"xts-section-heading xts-reset-mb-10 xts-reset-last xts-textalign-left\" data-animation-delay=\"\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<h4 class=\"xts-section-title title xts-design-default xts-fontsize-l\">\r\n\t\t\t\t\t\t<span class=\"xts-section-title-text\" data-elementor-setting-key=\"title\">\r\n\t\t\t\t\t\t\tProceso de fabricaci\u00f3n\t\t\t\t\t\t<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<\/h4>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-623e90f xts-scheme-inherit xts-textalign-inherit elementor-widget elementor-widget-text-editor\" data-id=\"623e90f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>El proceso de fabricaci\u00f3n de vasos de pl\u00e1stico comienza con pl\u00e1stico crudo, tratado especialmente para eliminar cualquier suciedad o bacteria. Posteriormente, se calienta a una temperatura espec\u00edfica y se vierte en moldes.<\/p>\n\n<p>La temperatura es especialmente importante, ya que si el pl\u00e1stico est\u00e1 demasiado caliente o demasiado fr\u00edo, puede quemarse o endurecerse. Las nuevas tecnolog\u00edas han hecho posible que las l\u00edneas de montaje produzcan en masa miles de vasos en una sola hora.<\/p>\n\n<p>Una vez secas las tazas, est\u00e1n listas para su embalaje, almacenamiento y transporte.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d97b56e elementor-section-boxed elementor-section-height-default elementor-section-height-default xts-section-disabled\" data-id=\"d97b56e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b092b74\" data-id=\"b092b74\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d3926e elementor-widget elementor-widget-xts_title\" data-id=\"1d3926e\" data-element_type=\"widget\" data-widget_type=\"xts_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"xts-section-heading xts-reset-mb-10 xts-reset-last xts-textalign-left\" data-animation-delay=\"\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<h4 class=\"xts-section-title title xts-design-default xts-fontsize-l\">\r\n\t\t\t\t\t\t<span class=\"xts-section-title-text\" data-elementor-setting-key=\"title\">\r\n\t\t\t\t\t\t\tVaso de pl\u00e1stico como regalo\t\t\t\t\t\t<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<\/h4>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58bad3e xts-scheme-inherit xts-textalign-inherit elementor-widget elementor-widget-text-editor\" data-id=\"58bad3e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>El vaso de pl\u00e1stico m\u00e1s recomendado para el consumo es el <a href=\"#\">Polipropileno<\/a>, ya que se puede usar con bebidas fr\u00edas o calientes (no es t\u00f3xico). El policarbonato es tambi\u00e9n una versi\u00f3n muy moderna del vaso de pl\u00e1stico, con la ventaja de ser m\u00e1s duradero y, en pesos m\u00e1s pesados, pr\u00e1cticamente id\u00e9ntico al vidrio.<\/p>\n\n<p>Por \u00faltimo, la taza ecol\u00f3gica o Eco Cup, que puede ser <a href=\"https:\/\/ecocopo.copopalhinhas.pt\/copos-reutilizaveis-vantagens\/\" target=\"_blank\" rel=\"noopener\">reutilizado<\/a> Docenas o cientos de veces se transforma luego f\u00e1cilmente en otros objetos.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba4791d elementor-section-boxed elementor-section-height-default elementor-section-height-default xts-section-disabled\" data-id=\"ba4791d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-818d259\" data-id=\"818d259\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53ee34d elementor-widget elementor-widget-xts_title\" data-id=\"53ee34d\" data-element_type=\"widget\" data-widget_type=\"xts_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"xts-section-heading xts-reset-mb-10 xts-reset-last xts-textalign-left\" data-animation-delay=\"\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<h4 class=\"xts-section-title title xts-design-default xts-fontsize-l\">\r\n\t\t\t\t\t\t<span class=\"xts-section-title-text\" data-elementor-setting-key=\"title\">\r\n\t\t\t\t\t\t\t\u00bfY el futuro?\t\t\t\t\t\t<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<\/h4>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dd37dd xts-scheme-inherit xts-textalign-inherit elementor-widget elementor-widget-text-editor\" data-id=\"3dd37dd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Las investigaciones sobre el pl\u00e1stico y c\u00f3mo reducir su impacto en el medio ambiente revelan algunos inventos interesantes que seguramente se reflejar\u00e1n tambi\u00e9n en los vasos de pl\u00e1stico.<\/p>\n<p>Vea algunos de ellos:<\/p>\n<ul>\n     <li><b>Pol\u00edmero a prueba de balas \u2013 <\/b> Cient\u00edficos de la Universidad Rice en Texas han creado un nuevo material que puede detener una bala de 9 mm y sellar el agujero que deja.<\/li>\n\n     <li><b>Sangre pl\u00e1stica \u2013<\/b> Desarrollado por la Universidad de Sheffield para imitar la hemoglobina, para su uso en situaciones de trauma donde se requiere un reemplazo r\u00e1pido de sangre.<\/li>\n\n     <li><b>C\u00e9lulas solares de pl\u00e1stico \u2013<\/b> Una c\u00e9lula solar de pol\u00edmero que puede producir electricidad a partir de la luz solar a trav\u00e9s del efecto fotovoltaico proporciona una alternativa ligera, desechable y econ\u00f3mica a los paneles solares tradicionales.<\/li>\n\n     <li><b>Pol\u00edmeros implantables -<\/b> Los biomateriales m\u00e9dicos e implantables, como el PEEK, se utilizan en aplicaciones neurol\u00f3gicas para ayudar a controlar la epilepsia, la enfermedad de Parkinson y las lesiones cerebrales traum\u00e1ticas.<\/li>\n\n     <li><b>Vuelos comerciales al espacio \u2013<\/b> Los materiales compuestos de carbono ligeros ser\u00e1n cruciales para realizar vuelos espaciales.<\/li>\n\n     <li><b>Pantallas de pl\u00e1stico flexibles \u2013<\/b> Los diodos org\u00e1nicos emisores de luz se colocan sobre papel pl\u00e1stico para crear dispositivos electr\u00f3nicos con pantallas flexibles.<\/li>\n\n     <li><b>Coches sin conductor \u2013<\/b> En el futuro, todos los veh\u00edculos sin conductor se construir\u00e1n casi en su totalidad con piezas de pl\u00e1stico debido a las propiedades ligeras que proporcionan.<\/li>\n<\/ul>\n\n<p>\u00a1Ahora imagina que el pl\u00e1stico que uses en el futuro se pudiera reciclar en diversos art\u00edculos a partir de estas innovaciones que rozan la ciencia ficci\u00f3n!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d91d21f elementor-widget elementor-widget-xts_button\" data-id=\"d91d21f\" data-element_type=\"widget\" data-widget_type=\"xts_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"xts-button-wrapper xts-textalign-left\" >\r\n\t\t\t\t\t\t\t\t\t<a class=\"xts-button xts-size-m xts-style-default xts-color-primary xts-shape-rectangle\"  href=\"#\">\r\n\t\t\t\t\t\t<span class=\"xts-button-text\" data-elementor-setting-key=\"button_text\">\r\n\t\t\t\t\t\t\tDESCUBRE NUESTRAS OPCIONES DE VASOS DE POLIPROPILENO AHORA MISMO\t\t\t\t\t\t<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>O copo pl\u00e1stico tornou o mundo diferente, sem d\u00favidas. Encontrados em est\u00e1dios e jogos desportivos, passando por piqueniques em fam\u00edlia, hospitais, escolas, eventos&#8230; A hist\u00f3ria dos copos de pl\u00e1stico remonta \u00e0 d\u00e9cada de 1960, mas antes da sua inven\u00e7\u00e3o, as pessoas usavam copos de papel de forma semelhante. Aqui resgatamos um pouco da hist\u00f3ria dos [&hellip;]<\/p>","protected":false},"author":1,"featured_media":3986,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[260],"tags":[265,262,263,261],"class_list":["post-381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-copo-plastico","tag-copo-plastico","tag-policarbonato","tag-poliestireno","tag-polipropileno"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v23.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A Evolu\u00e7\u00e3o do Copo Pl\u00e1stico - Copopalhinhas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev4copopalhinhas.devdg.pt\/es\/a-evolucao-do-copo-plastico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Evolu\u00e7\u00e3o do Copo Pl\u00e1stico\" \/>\n<meta property=\"og:description\" content=\"O copo pl\u00e1stico tornou o mundo diferente, sem d\u00favidas. Encontrados em est\u00e1dios e jogos desportivos, passando por piqueniques em fam\u00edlia, hospitais, escolas, eventos&#8230; A hist\u00f3ria dos copos de pl\u00e1stico remonta \u00e0 d\u00e9cada de 1960, mas antes da sua inven\u00e7\u00e3o, as pessoas usavam copos de papel de forma semelhante. Aqui resgatamos um pouco da hist\u00f3ria dos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev4copopalhinhas.devdg.pt\/es\/a-evolucao-do-copo-plastico\/\" \/>\n<meta property=\"og:site_name\" content=\"Copopalhinhas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/copopalhinhas\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-13T06:17:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-19T15:33:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/evolucao-copo-plastico-copopalhinhas.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"385\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Teste Digitalgreen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@copopalhinhas\" \/>\n<meta name=\"twitter:site\" content=\"@copopalhinhas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/\"},\"author\":{\"name\":\"Teste Digitalgreen\",\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/#\/schema\/person\/245b006992beb41b58b7619f7d94fcc0\"},\"headline\":\"A Evolu\u00e7\u00e3o do Copo Pl\u00e1stico\",\"datePublished\":\"2018-03-13T06:17:10+00:00\",\"dateModified\":\"2024-01-19T15:33:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/\"},\"wordCount\":1072,\"publisher\":{\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/#organization\"},\"image\":{\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/evolucao-copo-plastico-copopalhinhas.jpeg\",\"keywords\":[\"Copo Pl\u00e1stico\",\"Policarbonato\",\"Poliestireno\",\"Polipropileno\"],\"articleSection\":[\"Copo Pl\u00e1stico\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/\",\"url\":\"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/\",\"name\":\"A Evolu\u00e7\u00e3o do Copo Pl\u00e1stico - Copopalhinhas\",\"isPartOf\":{\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/evolucao-copo-plastico-copopalhinhas.jpeg\",\"datePublished\":\"2018-03-13T06:17:10+00:00\",\"dateModified\":\"2024-01-19T15:33:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/#primaryimage\",\"url\":\"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/evolucao-copo-plastico-copopalhinhas.jpeg\",\"contentUrl\":\"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/evolucao-copo-plastico-copopalhinhas.jpeg\",\"width\":770,\"height\":385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/dev4copopalhinhas.devdg.pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Evolu\u00e7\u00e3o do Copo Pl\u00e1stico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/#website\",\"url\":\"https:\/\/dev4copopalhinhas.devdg.pt\/\",\"name\":\"Copopalhinhas\",\"description\":\"Os Melhores Pre\u00e7os\",\"publisher\":{\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev4copopalhinhas.devdg.pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/#organization\",\"name\":\"Copopalhinhas\",\"url\":\"https:\/\/dev4copopalhinhas.devdg.pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2022\/05\/COPOPALHINHASlogo.png\",\"contentUrl\":\"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2022\/05\/COPOPALHINHASlogo.png\",\"width\":1200,\"height\":323,\"caption\":\"Copopalhinhas\"},\"image\":{\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/copopalhinhas\",\"https:\/\/x.com\/copopalhinhas\",\"https:\/\/copopalhinhas.blogspot.pt\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/#\/schema\/person\/245b006992beb41b58b7619f7d94fcc0\",\"name\":\"Teste Digitalgreen\",\"sameAs\":[\"https:\/\/dev4copopalhinhas.devdg.pt\"],\"url\":\"https:\/\/dev4copopalhinhas.devdg.pt\/es\/author\/admindigitalgreen-com-pt\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A Evolu\u00e7\u00e3o do Copo Pl\u00e1stico - Copopalhinhas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/a-evolucao-do-copo-plastico\/","og_locale":"es_ES","og_type":"article","og_title":"A Evolu\u00e7\u00e3o do Copo Pl\u00e1stico","og_description":"O copo pl\u00e1stico tornou o mundo diferente, sem d\u00favidas. Encontrados em est\u00e1dios e jogos desportivos, passando por piqueniques em fam\u00edlia, hospitais, escolas, eventos&#8230; A hist\u00f3ria dos copos de pl\u00e1stico remonta \u00e0 d\u00e9cada de 1960, mas antes da sua inven\u00e7\u00e3o, as pessoas usavam copos de papel de forma semelhante. Aqui resgatamos um pouco da hist\u00f3ria dos [&hellip;]","og_url":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/a-evolucao-do-copo-plastico\/","og_site_name":"Copopalhinhas","article_publisher":"https:\/\/www.facebook.com\/copopalhinhas","article_published_time":"2018-03-13T06:17:10+00:00","article_modified_time":"2024-01-19T15:33:38+00:00","og_image":[{"width":770,"height":385,"url":"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/evolucao-copo-plastico-copopalhinhas.jpeg","type":"image\/jpeg"}],"author":"Teste Digitalgreen","twitter_card":"summary_large_image","twitter_creator":"@copopalhinhas","twitter_site":"@copopalhinhas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/#article","isPartOf":{"@id":"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/"},"author":{"name":"Teste Digitalgreen","@id":"https:\/\/dev4copopalhinhas.devdg.pt\/#\/schema\/person\/245b006992beb41b58b7619f7d94fcc0"},"headline":"A Evolu\u00e7\u00e3o do Copo Pl\u00e1stico","datePublished":"2018-03-13T06:17:10+00:00","dateModified":"2024-01-19T15:33:38+00:00","mainEntityOfPage":{"@id":"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/"},"wordCount":1072,"publisher":{"@id":"https:\/\/dev4copopalhinhas.devdg.pt\/#organization"},"image":{"@id":"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/#primaryimage"},"thumbnailUrl":"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/evolucao-copo-plastico-copopalhinhas.jpeg","keywords":["Copo Pl\u00e1stico","Policarbonato","Poliestireno","Polipropileno"],"articleSection":["Copo Pl\u00e1stico"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/","url":"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/","name":"A Evolu\u00e7\u00e3o do Copo Pl\u00e1stico - Copopalhinhas","isPartOf":{"@id":"https:\/\/dev4copopalhinhas.devdg.pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/#primaryimage"},"image":{"@id":"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/#primaryimage"},"thumbnailUrl":"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/evolucao-copo-plastico-copopalhinhas.jpeg","datePublished":"2018-03-13T06:17:10+00:00","dateModified":"2024-01-19T15:33:38+00:00","breadcrumb":{"@id":"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/#primaryimage","url":"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/evolucao-copo-plastico-copopalhinhas.jpeg","contentUrl":"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2018\/03\/evolucao-copo-plastico-copopalhinhas.jpeg","width":770,"height":385},{"@type":"BreadcrumbList","@id":"https:\/\/dev4copopalhinhas.devdg.pt\/a-evolucao-do-copo-plastico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/dev4copopalhinhas.devdg.pt\/"},{"@type":"ListItem","position":2,"name":"A Evolu\u00e7\u00e3o do Copo Pl\u00e1stico"}]},{"@type":"WebSite","@id":"https:\/\/dev4copopalhinhas.devdg.pt\/#website","url":"https:\/\/dev4copopalhinhas.devdg.pt\/","name":"Pajitas para vasos","description":"Los mejores precios","publisher":{"@id":"https:\/\/dev4copopalhinhas.devdg.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev4copopalhinhas.devdg.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/dev4copopalhinhas.devdg.pt\/#organization","name":"Pajitas para vasos","url":"https:\/\/dev4copopalhinhas.devdg.pt\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dev4copopalhinhas.devdg.pt\/#\/schema\/logo\/image\/","url":"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2022\/05\/COPOPALHINHASlogo.png","contentUrl":"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2022\/05\/COPOPALHINHASlogo.png","width":1200,"height":323,"caption":"Copopalhinhas"},"image":{"@id":"https:\/\/dev4copopalhinhas.devdg.pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/copopalhinhas","https:\/\/x.com\/copopalhinhas","https:\/\/copopalhinhas.blogspot.pt\/"]},{"@type":"Person","@id":"https:\/\/dev4copopalhinhas.devdg.pt\/#\/schema\/person\/245b006992beb41b58b7619f7d94fcc0","name":"Prueba digital verde","sameAs":["https:\/\/dev4copopalhinhas.devdg.pt"],"url":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/author\/admindigitalgreen-com-pt\/"}]}},"_links":{"self":[{"href":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/wp-json\/wp\/v2\/posts\/381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/wp-json\/wp\/v2\/comments?post=381"}],"version-history":[{"count":0,"href":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/wp-json\/wp\/v2\/posts\/381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/wp-json\/wp\/v2\/media\/3986"}],"wp:attachment":[{"href":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/wp-json\/wp\/v2\/media?parent=381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/wp-json\/wp\/v2\/categories?post=381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/wp-json\/wp\/v2\/tags?post=381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}