{"id":2020,"count":2,"description":"LOU\u00c7AS REUTILIZ\u00c1VEIS SAN: Durabilidade e Eleg\u00e2ncia para Todos os Momentos\r\n\r\nAs lou\u00e7as reutiliz\u00e1veis SAN oferecem a apar\u00eancia da cer\u00e2mica com a resist\u00eancia e durabilidade do pl\u00e1stico. Ideais para restaurantes, eventos ou uso di\u00e1rio, essas lou\u00e7as combinam praticidade e eleg\u00e2ncia, proporcionando uma solu\u00e7\u00e3o ecol\u00f3gica e resistente. F\u00e1ceis de limpar e seguras, elas oferecem uma alternativa robusta aos produtos descart\u00e1veis, mantendo a qualidade e o estilo em qualquer ocasi\u00e3o.","link":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/categorias\/loucas-reutilizaveis-san\/","name":"LOU\u00c7AS REUTILIZ\u00c1VEIS SAN","slug":"loucas-reutilizaveis-san","taxonomy":"product_cat","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v23.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LOU\u00c7AS REUTILIZ\u00c1VEIS SAN - Copopalhinhas<\/title>\n<meta name=\"description\" content=\"As lou\u00e7as reutiliz\u00e1veis SAN oferecem a resist\u00eancia e durabilidade do pl\u00e1stico. S\u00e3o f\u00e1ceis de limpar e podem ir \u00e1 m\u00e1quina de lavar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev4copopalhinhas.devdg.pt\/es\/categorias\/loucas-reutilizaveis-san\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LOU\u00c7AS REUTILIZ\u00c1VEIS SAN\" \/>\n<meta property=\"og:description\" content=\"As lou\u00e7as reutiliz\u00e1veis SAN oferecem a resist\u00eancia e durabilidade do pl\u00e1stico. S\u00e3o f\u00e1ceis de limpar e podem ir \u00e1 m\u00e1quina de lavar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev4copopalhinhas.devdg.pt\/es\/categorias\/loucas-reutilizaveis-san\/\" \/>\n<meta property=\"og:site_name\" content=\"Copopalhinhas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@copopalhinhas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/categorias\/loucas-reutilizaveis-san\/\",\"url\":\"https:\/\/dev4copopalhinhas.devdg.pt\/categorias\/loucas-reutilizaveis-san\/\",\"name\":\"LOU\u00c7AS REUTILIZ\u00c1VEIS SAN - Copopalhinhas\",\"isPartOf\":{\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/#website\"},\"description\":\"As lou\u00e7as reutiliz\u00e1veis SAN oferecem a resist\u00eancia e durabilidade do pl\u00e1stico. S\u00e3o f\u00e1ceis de limpar e podem ir \u00e1 m\u00e1quina de lavar.\",\"breadcrumb\":{\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/categorias\/loucas-reutilizaveis-san\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/categorias\/loucas-reutilizaveis-san\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/dev4copopalhinhas.devdg.pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LOU\u00c7AS REUTILIZ\u00c1VEIS SAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/#website\",\"url\":\"https:\/\/dev4copopalhinhas.devdg.pt\/\",\"name\":\"Copopalhinhas\",\"description\":\"Os Melhores Pre\u00e7os\",\"publisher\":{\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev4copopalhinhas.devdg.pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/#organization\",\"name\":\"Copopalhinhas\",\"url\":\"https:\/\/dev4copopalhinhas.devdg.pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2022\/05\/COPOPALHINHASlogo.png\",\"contentUrl\":\"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2022\/05\/COPOPALHINHASlogo.png\",\"width\":1200,\"height\":323,\"caption\":\"Copopalhinhas\"},\"image\":{\"@id\":\"https:\/\/dev4copopalhinhas.devdg.pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/copopalhinhas\",\"https:\/\/x.com\/copopalhinhas\",\"https:\/\/copopalhinhas.blogspot.pt\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"LOU\u00c7AS REUTILIZ\u00c1VEIS SAN - Copopalhinhas","description":"As lou\u00e7as reutiliz\u00e1veis SAN oferecem a resist\u00eancia e durabilidade do pl\u00e1stico. S\u00e3o f\u00e1ceis de limpar e podem ir \u00e1 m\u00e1quina de lavar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/categorias\/loucas-reutilizaveis-san\/","og_locale":"es_ES","og_type":"article","og_title":"LOU\u00c7AS REUTILIZ\u00c1VEIS SAN","og_description":"As lou\u00e7as reutiliz\u00e1veis SAN oferecem a resist\u00eancia e durabilidade do pl\u00e1stico. S\u00e3o f\u00e1ceis de limpar e podem ir \u00e1 m\u00e1quina de lavar.","og_url":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/categorias\/loucas-reutilizaveis-san\/","og_site_name":"Copopalhinhas","twitter_card":"summary_large_image","twitter_site":"@copopalhinhas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/dev4copopalhinhas.devdg.pt\/categorias\/loucas-reutilizaveis-san\/","url":"https:\/\/dev4copopalhinhas.devdg.pt\/categorias\/loucas-reutilizaveis-san\/","name":"LOU\u00c7AS REUTILIZ\u00c1VEIS SAN - Copopalhinhas","isPartOf":{"@id":"https:\/\/dev4copopalhinhas.devdg.pt\/#website"},"description":"As lou\u00e7as reutiliz\u00e1veis SAN oferecem a resist\u00eancia e durabilidade do pl\u00e1stico. S\u00e3o f\u00e1ceis de limpar e podem ir \u00e1 m\u00e1quina de lavar.","breadcrumb":{"@id":"https:\/\/dev4copopalhinhas.devdg.pt\/categorias\/loucas-reutilizaveis-san\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/dev4copopalhinhas.devdg.pt\/categorias\/loucas-reutilizaveis-san\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/dev4copopalhinhas.devdg.pt\/"},{"@type":"ListItem","position":2,"name":"LOU\u00c7AS REUTILIZ\u00c1VEIS SAN"}]},{"@type":"WebSite","@id":"https:\/\/dev4copopalhinhas.devdg.pt\/#website","url":"https:\/\/dev4copopalhinhas.devdg.pt\/","name":"Pajitas para vasos","description":"Os Melhores Pre\u00e7os","publisher":{"@id":"https:\/\/dev4copopalhinhas.devdg.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev4copopalhinhas.devdg.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/dev4copopalhinhas.devdg.pt\/#organization","name":"Pajitas para vasos","url":"https:\/\/dev4copopalhinhas.devdg.pt\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dev4copopalhinhas.devdg.pt\/#\/schema\/logo\/image\/","url":"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2022\/05\/COPOPALHINHASlogo.png","contentUrl":"https:\/\/dev4copopalhinhas.devdg.pt\/wp-content\/uploads\/2022\/05\/COPOPALHINHASlogo.png","width":1200,"height":323,"caption":"Copopalhinhas"},"image":{"@id":"https:\/\/dev4copopalhinhas.devdg.pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/copopalhinhas","https:\/\/x.com\/copopalhinhas","https:\/\/copopalhinhas.blogspot.pt\/"]}]}},"_links":{"self":[{"href":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/wp-json\/wp\/v2\/product_cat\/2020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/dev4copopalhinhas.devdg.pt\/es\/wp-json\/wp\/v2\/product?product_cat=2020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}